{"id":118361,"date":"2021-01-27T05:31:15","date_gmt":"2021-01-27T02:31:15","guid":{"rendered":"https:\/\/sinuepood.ee\/product\/hernesupp-300g\/"},"modified":"2026-05-13T19:11:09","modified_gmt":"2026-05-13T16:11:09","slug":"hernesupp-300g","status":"publish","type":"product","link":"https:\/\/sinuepood.ee\/ru\/product\/hernesupp-300g\/","title":{"rendered":"HERNESUPP 300G"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":118362,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[103],"product_tag":[],"class_list":{"0":"post-118361","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-jahutatud_valmistoidud","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>HERNESUPP 300G - Sinu Pood - E-pood<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sinuepood.ee\/ru\/product\/hernesupp-300g\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HERNESUPP 300G - Sinu Pood - E-pood\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sinuepood.ee\/ru\/product\/hernesupp-300g\/\" \/>\n<meta property=\"og:site_name\" content=\"Sinu Pood - E-pood\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T16:11:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sinuepood.ee\/wp-content\/uploads\/product_images\/4740184500113.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sinuepood.ee\/ru\/product\/hernesupp-300g\/\",\"url\":\"https:\/\/sinuepood.ee\/ru\/product\/hernesupp-300g\/\",\"name\":\"HERNESUPP 300G - Sinu Pood - E-pood\",\"isPartOf\":{\"@id\":\"https:\/\/sinuepood.ee\/ru\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sinuepood.ee\/ru\/product\/hernesupp-300g\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sinuepood.ee\/ru\/product\/hernesupp-300g\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sinuepood.ee\/wp-content\/uploads\/product_images\/4740184500113.jpg\",\"datePublished\":\"2021-01-27T02:31:15+00:00\",\"dateModified\":\"2026-05-13T16:11:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sinuepood.ee\/ru\/product\/hernesupp-300g\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sinuepood.ee\/ru\/product\/hernesupp-300g\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\/\/sinuepood.ee\/ru\/product\/hernesupp-300g\/#primaryimage\",\"url\":\"https:\/\/sinuepood.ee\/wp-content\/uploads\/product_images\/4740184500113.jpg\",\"contentUrl\":\"https:\/\/sinuepood.ee\/wp-content\/uploads\/product_images\/4740184500113.jpg\",\"width\":600,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sinuepood.ee\/ru\/product\/hernesupp-300g\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/sinuepood.ee\/ru\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/sinuepood.ee\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"HERNESUPP 300G\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sinuepood.ee\/ru\/#website\",\"url\":\"https:\/\/sinuepood.ee\/ru\/\",\"name\":\"Sinu Pood - E-pood\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sinuepood.ee\/ru\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"HERNESUPP 300G - Sinu Pood - E-pood","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sinuepood.ee\/ru\/product\/hernesupp-300g\/","og_locale":"ru_RU","og_type":"article","og_title":"HERNESUPP 300G - Sinu Pood - E-pood","og_url":"https:\/\/sinuepood.ee\/ru\/product\/hernesupp-300g\/","og_site_name":"Sinu Pood - E-pood","article_modified_time":"2026-05-13T16:11:09+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/sinuepood.ee\/wp-content\/uploads\/product_images\/4740184500113.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sinuepood.ee\/ru\/product\/hernesupp-300g\/","url":"https:\/\/sinuepood.ee\/ru\/product\/hernesupp-300g\/","name":"HERNESUPP 300G - Sinu Pood - E-pood","isPartOf":{"@id":"https:\/\/sinuepood.ee\/ru\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sinuepood.ee\/ru\/product\/hernesupp-300g\/#primaryimage"},"image":{"@id":"https:\/\/sinuepood.ee\/ru\/product\/hernesupp-300g\/#primaryimage"},"thumbnailUrl":"https:\/\/sinuepood.ee\/wp-content\/uploads\/product_images\/4740184500113.jpg","datePublished":"2021-01-27T02:31:15+00:00","dateModified":"2026-05-13T16:11:09+00:00","breadcrumb":{"@id":"https:\/\/sinuepood.ee\/ru\/product\/hernesupp-300g\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sinuepood.ee\/ru\/product\/hernesupp-300g\/"]}]},{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/sinuepood.ee\/ru\/product\/hernesupp-300g\/#primaryimage","url":"https:\/\/sinuepood.ee\/wp-content\/uploads\/product_images\/4740184500113.jpg","contentUrl":"https:\/\/sinuepood.ee\/wp-content\/uploads\/product_images\/4740184500113.jpg","width":600,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/sinuepood.ee\/ru\/product\/hernesupp-300g\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sinuepood.ee\/ru\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/sinuepood.ee\/shop\/"},{"@type":"ListItem","position":3,"name":"HERNESUPP 300G"}]},{"@type":"WebSite","@id":"https:\/\/sinuepood.ee\/ru\/#website","url":"https:\/\/sinuepood.ee\/ru\/","name":"Sinu Pood - E-pood","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sinuepood.ee\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"}]}},"_links":{"self":[{"href":"https:\/\/sinuepood.ee\/ru\/wp-json\/wp\/v2\/product\/118361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sinuepood.ee\/ru\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sinuepood.ee\/ru\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sinuepood.ee\/ru\/wp-json\/wp\/v2\/media\/118362"}],"wp:attachment":[{"href":"https:\/\/sinuepood.ee\/ru\/wp-json\/wp\/v2\/media?parent=118361"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/sinuepood.ee\/ru\/wp-json\/wp\/v2\/product_brand?post=118361"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/sinuepood.ee\/ru\/wp-json\/wp\/v2\/product_cat?post=118361"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/sinuepood.ee\/ru\/wp-json\/wp\/v2\/product_tag?post=118361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}